{"id":14613,"date":"2023-12-16T06:00:00","date_gmt":"2023-12-16T05:00:00","guid":{"rendered":"https:\/\/www.estudiahosteleria.com\/blog\/?p=14613"},"modified":"2024-01-16T14:26:51","modified_gmt":"2024-01-16T13:26:51","slug":"funciones-sumiller","status":"publish","type":"post","link":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller","title":{"rendered":"Qu\u00e9 funciones desempe\u00f1a un sumiller"},"content":{"rendered":"\n<p>Si hay una <strong>figura que resulta imprescindible en hosteler\u00eda<\/strong> es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las vinotecas o ejerciendo como cr\u00edtico gastron\u00f3mico.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 es un sumiller<\/h2>\n\n\n\n<p>La RAE define el t\u00e9rmino sumiller como la \u201c<strong><em>Persona experta en vinos y licores<\/em><\/strong><em> que, en los grandes hoteles, restaurantes, etc., sugiere a los clientes la bebida apropiada para la ocasi\u00f3n<\/em>.\u201d<\/p>\n\n\n\n<p>Si queremos analizar <strong>el origen<\/strong> de esta figura tenemos que retrotraernos hasta <strong>la Edad Media<\/strong>. Fue Felipe V el primero que introdujo esta figura en la corte, su funci\u00f3n era la de probar el vino que se le iba a servir al monarca para evitar envenenamientos.<\/p>\n\n\n\n<p>Hoy en d\u00eda, su principal funci\u00f3n dentro de los negocios de hosteler\u00eda es la de <strong>asesorar a los clientes <\/strong>sobre el mejor vino a combinar con los alimentos<\/p>\n\n\n\n<p> En realidad, se encarga de los servicios que tienen que ver con el vino dentro del restaurante. Se trata de un profesional que tiene que tener <strong>profundos conocimientos<\/strong> de ampelograf\u00eda (es decir de todo lo relativo a las vides y los vi\u00f1edos), de las cosechas y \u00f1as crianzas de vinos, de la geograf\u00eda vit\u00edcola, de los productores, las denominaciones de origen, de enolog\u00eda, etc.<\/p>\n\n\n\n<p>Todo ello implica que tiene que tener una <strong>importante formaci\u00f3n acad\u00e9mica<\/strong> que abarca muchas ramas.<\/p>\n\n\n\n<p>En la actualidad, el sumiller puede realizar <strong>m\u00e1s funciones<\/strong> que las de trabajar en un restaurante. Entre ellas podemos enumerar:<\/p>\n\n\n\n<ul>\n<li>Ejercer como <strong>cr\u00edtico de vinos<\/strong>.<\/li>\n\n\n\n<li>Trabajar como consultor especializado en todo lo que tiene que ver con los vinos.<\/li>\n\n\n\n<li>Ser un escritor especializado<\/li>\n\n\n\n<li>Trabajar como <strong>educador<\/strong> para acercar el mundo del vino al p\u00fablico.<\/li>\n\n\n\n<li>Realizar catas y degustaciones<\/li>\n<\/ul>\n\n\n\n<p>Un buen sumiller <strong>ser\u00e1 un asesor confiable y objetivo<\/strong>, en este sentido lo que primar\u00e1 ser\u00e1 el placer del cliente centr\u00e1ndose en su elecci\u00f3n culinaria y en lo que est\u00e9 dispuesto a invertir.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Qu\u00e9 funciones realiza en un restaurante<\/h2>\n\n\n\n<p>Las funciones que ejerce un sumiller <strong>dentro de un restaurante<\/strong> pueden resumirse en:<\/p>\n\n\n\n<ul>\n<li><strong>Aconsejar<\/strong> a cada cliente que lo demande sobre cu\u00e1l es el vino ideal para acompa\u00f1ar sus platos.<\/li>\n\n\n\n<li>Descorchar y servir el vino siguiendo los pasos que marca el protocolo.<\/li>\n\n\n\n<li>Controlar la temperatura y las caracter\u00edsticas de los vinos para <strong>asegurarse de que lleguen en perfecto estado al servicio.<\/strong><\/li>\n\n\n\n<li>Mantener en perfecto estado la bodega de vinos cuidando de las condiciones de temperatura, humedad, luz, etc.<\/li>\n\n\n\n<li>Seleccionar y <strong>elaborar la carta de vinos del local<\/strong>, adem\u00e1s de controlar el stock.<\/li>\n\n\n\n<li>Formar al personal con el que trabaja en el sal\u00f3n.<\/li>\n<\/ul>\n\n\n\n<p>Para todo esto, un buen sumiller no solo debe tener una <strong>formaci\u00f3n exquisita<\/strong> y estar al tanto de todas las novedades que vayan surgiendo sobre la materia.<\/p>\n\n\n\n<p>Sino que adem\u00e1s, debe hacer gala de algunas actitudes como ser una persona creativa, sensible, <strong>que sepa comunicar <\/strong>y expresarse correctamente, que demuestre empat\u00eda, que sea curioso y aprecie la innovaci\u00f3n y la originalidad.<\/p>\n\n\n\n<p>Son muchos los sumilleres que para culminar su formaci\u00f3n viajan por todo el mundo para probar los vinos y que no dudan en asistir a convenciones gastron\u00f3micas y vin\u00edcolas.<\/p>\n\n\n\n<p>Gracias a nuestro <a href=\"https:\/\/www.estudiahosteleria.com\/enologia\/curso-superior-sumilleria?piloto=W74\">Curso Superior de Sumiller\u00eda<\/a> adquirir\u00e1s los conocimientos necesarios para convertirte en responsable de una bodega o del servicio de vinos y maridaje de un gran restaurante, adquiriendo la destreza sensorial para el reconocimiento de los diferentes productos.<\/p>\n\n\n\n<p><span class=\"Apple-converted-space\"> <span class=\"Apple-converted-space\">Si deseas especializarte en el mundo del vino, <a href=\"https:\/\/www.estudiahosteleria.com\/enologia?piloto=w74\" target=\"_blank\" rel=\"noreferrer noopener\">esta es la formaci\u00f3n online en Enolog\u00eda que estabas buscando.<\/a><\/span> <\/span><\/p>\n\n\n\n<div class=\"wp-block-buttons is-horizontal is-content-justification-center is-layout-flex wp-container-2\">\n<div class=\"wp-block-button\"><a class=\"wp-block-button__link has-white-color has-text-color has-background wp-element-button\" href=\"https:\/\/www.estudiahosteleria.com\/enologia?piloto=w77\" style=\"border-radius:9px;background-color:#6d0c14\" target=\"_blank\" rel=\"noreferrer noopener\">\u00a1Inf\u00f3rmate sin compromiso!<\/a><\/div>\n<\/div>\n\n\n\n<hr class=\"wp-block-separator has-css-opacity\"\/>\n\n\n\n<p id=\"block-8196dfea-5659-4ffa-914a-25f9c70249d4\"><br>Si te ha parecido interesante este post y quieres ampliar conocimientos o promocionar en tu profesi\u00f3n&nbsp;te animamos a leer otros post de nuestro blog.<br>Recuerda que en&nbsp;<strong>ESAH<\/strong> ofrecemos una formaci\u00f3n espec\u00edfica en Hosteler\u00eda, Turismo, Enolog\u00eda, Gesti\u00f3n y Direcci\u00f3n, Organizaci\u00f3n de Eventos, Pasteler\u00eda y Cocina, puedes consultar toda nuestra oferta formativa en nuestra web: <a href=\"https:\/\/www.estudiahosteleria.com\/?piloto=w74\" target=\"_blank\" rel=\"noreferrer noopener\">www.estudiahosteleria.com<\/a><\/p>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.estudiahosteleria.com\/enologia?piloto=w74\"><img decoding=\"async\" loading=\"lazy\" width=\"637\" height=\"90\" src=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2021\/06\/637x90_mst_enologia.jpg\" alt=\"\" class=\"wp-image-14172\" srcset=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2021\/06\/637x90_mst_enologia.jpg 637w, https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2021\/06\/637x90_mst_enologia-300x42.jpg 300w\" sizes=\"(max-width: 637px) 100vw, 637px\" \/><\/a><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las vinotecas o ejerciendo como cr\u00edtico gastron\u00f3mico. Qu\u00e9 es un sumiller La RAE define el t\u00e9rmino sumiller como la \u201cPersona experta en vinos y licores que, en los grandes hoteles, restaurantes, etc., sugiere a los clientes la bebida apropiada para la ocasi\u00f3n.\u201d Si queremos analizar el origen de esta figura tenemos que retrotraernos hasta la Edad Media. Fue Felipe V el primero que introdujo esta figura en la corte, su funci\u00f3n era la de probar el vino que se le iba a servir al monarca para evitar envenenamientos. Hoy en d\u00eda, su principal funci\u00f3n dentro de los negocios de hosteler\u00eda es la de asesorar a los clientes sobre el mejor vino a combinar con los alimentos En realidad, se encarga de los servicios que tienen que ver con el vino dentro del restaurante. Se trata de un profesional que tiene que tener profundos conocimientos de ampelograf\u00eda (es decir de todo lo relativo a las vides y los vi\u00f1edos), de las cosechas y \u00f1as crianzas de vinos, de la geograf\u00eda vit\u00edcola, de los productores, las denominaciones de [&hellip;]<\/p>\n","protected":false},"author":35,"featured_media":14615,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[417],"tags":[1881,356,1348],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller<\/title>\n<meta name=\"description\" content=\"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller\" \/>\n<meta property=\"og:description\" content=\"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\" \/>\n<meta property=\"og:site_name\" content=\"Blog de la Escuela ESAH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CampusSEAS\" \/>\n<meta property=\"article:published_time\" content=\"2023-12-16T05:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-16T13:26:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2021\/10\/sumiller.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Ana Reb\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Campus_SEAS\" \/>\n<meta name=\"twitter:site\" content=\"@Campus_SEAS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Ana Reb\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\"},\"author\":{\"name\":\"Ana Reb\u00f3n\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/f7f9391e11113d0ed818f18383af9ca2\"},\"headline\":\"Qu\u00e9 funciones desempe\u00f1a un sumiller\",\"datePublished\":\"2023-12-16T05:00:00+00:00\",\"dateModified\":\"2024-01-16T13:26:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\"},\"wordCount\":683,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\"},\"keywords\":[\"curso superior de sumiller\u00eda\",\"Sumiller\",\"sumilleria\"],\"articleSection\":[\"Enolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\",\"name\":\"Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller\",\"isPartOf\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#website\"},\"datePublished\":\"2023-12-16T05:00:00+00:00\",\"dateModified\":\"2024-01-16T13:26:51+00:00\",\"description\":\"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#website\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/\",\"name\":\"Blog de la Escuela ESAH\",\"description\":\"Blog de la Escuela ESAH, Estudios Superiores Abiertos de Hosteleria\",\"publisher\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estudiahosteleria.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\",\"name\":\"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg\",\"contentUrl\":\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg\",\"width\":512,\"height\":512,\"caption\":\"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda\"},\"image\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CampusSEAS\",\"https:\/\/twitter.com\/Campus_SEAS\",\"https:\/\/www.instagram.com\/campus_seas\",\"http:\/\/www.linkedin.com\/company\/seas-estudios-superiores-abiertos\",\"https:\/\/www.youtube.com\/@Campus_SEAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/f7f9391e11113d0ed818f18383af9ca2\",\"name\":\"Ana Reb\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/9594d6208061ad1eddc95db511642fe5?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/9594d6208061ad1eddc95db511642fe5?s=96&r=g\",\"caption\":\"Ana Reb\u00f3n\"},\"description\":\"ESAH, Estudios Superiores Abiertos de Hosteler\u00eda es la escuela de restauraci\u00f3n y turismo online de referencia a nivel internacional de La Escuela de Hosteler\u00eda de Sevilla,\u00a0el Grupo Lezama, y SEAS, Estudios Superiores Abiertos (Grupo San Valero). Visita\u00a0EstudiaHosteleria.com\u00a0para consultar nuestra oferta formativa de\u00a0cursos y m\u00e1sters.\u00a0Formaci\u00f3n profesional para el empleo de calidad y accesible para todos.\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/author\/ana-rebon\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller","description":"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller","og_locale":"es_ES","og_type":"article","og_title":"Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller","og_description":"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las","og_url":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller","og_site_name":"Blog de la Escuela ESAH","article_publisher":"https:\/\/www.facebook.com\/CampusSEAS","article_published_time":"2023-12-16T05:00:00+00:00","article_modified_time":"2024-01-16T13:26:51+00:00","og_image":[{"width":637,"height":240,"url":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2021\/10\/sumiller.jpg","type":"image\/jpeg"}],"author":"Ana Reb\u00f3n","twitter_card":"summary_large_image","twitter_creator":"@Campus_SEAS","twitter_site":"@Campus_SEAS","twitter_misc":{"Escrito por":"Ana Reb\u00f3n","Tiempo de lectura":"4 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller#article","isPartOf":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller"},"author":{"name":"Ana Reb\u00f3n","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/f7f9391e11113d0ed818f18383af9ca2"},"headline":"Qu\u00e9 funciones desempe\u00f1a un sumiller","datePublished":"2023-12-16T05:00:00+00:00","dateModified":"2024-01-16T13:26:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller"},"wordCount":683,"commentCount":0,"publisher":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization"},"keywords":["curso superior de sumiller\u00eda","Sumiller","sumilleria"],"articleSection":["Enolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller","url":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller","name":"Enolog\u00eda - Qu\u00e9 funciones desempe\u00f1a un sumiller","isPartOf":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#website"},"datePublished":"2023-12-16T05:00:00+00:00","dateModified":"2024-01-16T13:26:51+00:00","description":"Si hay una figura que resulta imprescindible en hosteler\u00eda es la del sumiller. Est\u00e1 presente en los restaurantes, pero tambi\u00e9n en los gastrobares, en las","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estudiahosteleria.com\/blog\/enologia\/funciones-sumiller"]}]},{"@type":"WebSite","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#website","url":"https:\/\/www.estudiahosteleria.com\/blog\/","name":"Blog de la Escuela ESAH","description":"Blog de la Escuela ESAH, Estudios Superiores Abiertos de Hosteleria","publisher":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estudiahosteleria.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization","name":"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda","url":"https:\/\/www.estudiahosteleria.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg","contentUrl":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg","width":512,"height":512,"caption":"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda"},"image":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CampusSEAS","https:\/\/twitter.com\/Campus_SEAS","https:\/\/www.instagram.com\/campus_seas","http:\/\/www.linkedin.com\/company\/seas-estudios-superiores-abiertos","https:\/\/www.youtube.com\/@Campus_SEAS"]},{"@type":"Person","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/f7f9391e11113d0ed818f18383af9ca2","name":"Ana Reb\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/9594d6208061ad1eddc95db511642fe5?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/9594d6208061ad1eddc95db511642fe5?s=96&r=g","caption":"Ana Reb\u00f3n"},"description":"ESAH, Estudios Superiores Abiertos de Hosteler\u00eda es la escuela de restauraci\u00f3n y turismo online de referencia a nivel internacional de La Escuela de Hosteler\u00eda de Sevilla,\u00a0el Grupo Lezama, y SEAS, Estudios Superiores Abiertos (Grupo San Valero). Visita\u00a0EstudiaHosteleria.com\u00a0para consultar nuestra oferta formativa de\u00a0cursos y m\u00e1sters.\u00a0Formaci\u00f3n profesional para el empleo de calidad y accesible para todos.","url":"https:\/\/www.estudiahosteleria.com\/blog\/author\/ana-rebon"}]}},"_links":{"self":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/14613"}],"collection":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/users\/35"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/comments?post=14613"}],"version-history":[{"count":4,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/14613\/revisions"}],"predecessor-version":[{"id":17608,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/14613\/revisions\/17608"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/media\/14615"}],"wp:attachment":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/media?parent=14613"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/categories?post=14613"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/tags?post=14613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}