{"id":7453,"date":"2016-12-15T09:30:43","date_gmt":"2016-12-15T08:30:43","guid":{"rendered":"https:\/\/www.estudiahosteleria.com\/blog\/?p=7453"},"modified":"2016-12-21T11:40:42","modified_gmt":"2016-12-21T10:40:42","slug":"los-mejores-vinos-para-esta-navidad-2016","status":"publish","type":"post","link":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016","title":{"rendered":"Los mejores vinos para esta Navidad 2016"},"content":{"rendered":"<p align=\"justify\">En este art\u00edculo le vamos a dar todo el protagonismo a los vinos y los espumosos que tomaremos estas Navidades, algo esencial que debe ayudar a potenciar la comida que serviremos o tomaremos y que haga disfrutar a todos nuestros invitados.<\/p>\n<p align=\"justify\"><strong>Vamos a dar unas peque\u00f1as pistas para elegir el vino y estar seguros de acertar al 100%.<\/strong><\/p>\n<p align=\"justify\">Lo primero de todo es conocer los <strong>gustos de los invitados<\/strong>, puesto que es la parte m\u00e1s importante de estas celebraciones.<\/p>\n<p align=\"justify\">Lo f\u00e1cil es comprar vinos de marcas comerciales y que podemos encontrar en muchas l\u00edneas de supermercados, pero no siempre es lo ideal para esto d\u00edas, puesto que si lo puedo beber cualquier d\u00eda, esa noche no le daremos importancia.<\/p>\n<p align=\"justify\"><strong>Deber\u00edamos tener vino blanco, tinto y un espumoso.<\/strong><\/p>\n<h3 style=\"text-align: right;\" align=\"justify\">VINO BLANCO NAVIDAD 2016<\/h3>\n<p align=\"justify\"><img decoding=\"async\" loading=\"lazy\" class=\"alignleft wp-image-7537\" src=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/frizzante-134x300.jpg\" width=\"80\" height=\"179\" srcset=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/frizzante-134x300.jpg 134w, https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/frizzante.jpg 234w\" sizes=\"(max-width: 80px) 100vw, 80px\" \/>Para el <strong>vino blanco<\/strong>, deber\u00edamos apostar por un vino con fruta, arom\u00e1tico y suave. Para salirnos<br \/>\nde lo m\u00e1s conocido, podr\u00edamos tener un vinos de la zona de Huelva, de uva <strong>Zalema o un Godello<\/strong>\u00a0de la zona de Galicia, la cual es suave y agradecida con la comida fresca, ligera y salada, como son los mariscos, ensaladas y maridados.<\/p>\n<p align=\"justify\">Dentro de los blancos, podr\u00edamos tambi\u00e9n decantarnos por un <strong>Frizzante<\/strong>, los cuales est\u00e1n de moda y tienen ese toque carb\u00f3nico, semidulce y con poca graduaci\u00f3n que los hace muy apetecibles.<\/p>\n<h3 style=\"text-align: right;\" align=\"justify\">VINO TINTO NAVIDAD 2016<\/h3>\n<p align=\"justify\">En los <strong>vinos tintos<\/strong> deber\u00edamos alejarnos de los vinos pesados, con una gran carga de madera, t\u00e1nicos <img decoding=\"async\" loading=\"lazy\" class=\"alignright wp-image-7535\" src=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/garnacha-centenaria-120x300.png\" width=\"80\" height=\"200\" srcset=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/garnacha-centenaria-120x300.png 120w, https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/garnacha-centenaria.png 240w\" sizes=\"(max-width: 80px) 100vw, 80px\" \/>y de gran potencia, puesto que con la carga de comida y bebida que llevamos, esos vinos pueden ser demasiado pesados y no adaptarse.<\/p>\n<p align=\"justify\">Pero s\u00ed podr\u00edamos apostar por vinos con cuerpo, pero con gran fruta, acidez y largo en boca. Por ejemplo podr\u00edamos apostar por vinos tintos de la<strong> zona de C\u00e1diz<\/strong> con uva Syrah, e incluso, porque no elegir un vino de <strong>zona del Bierzo<\/strong> de uva Menc\u00eda, que, como dice una buena amiga, son vinos frutales y muy sabrosos.<\/p>\n<p align=\"justify\">Tambi\u00e9n un garnacha de la <strong>zona de Arag\u00f3n<\/strong>, un Ayles o un Garnacha Centenaria, nunca falla. Tambi\u00e9n los vinos de Calatayud, que cada vez son mejores.<\/p>\n<h3 style=\"text-align: right;\" align=\"justify\">ESPUMOSO NAVIDAD 2016<\/h3>\n<p align=\"justify\">Para el brindis final, un espumoso. Pero si recordamos, muchas veces cuando brindamos con un espumoso, le damos un sorbo y el resto se queda en la copa. Para evitar esto, podemos elegir un Cava, Champagne o espumoso con uva Pinot Noir y si le queremos dar un<strong> toque m\u00e1s elegante y original lo podemos elegir rosado<\/strong>. Comentar que este espumoso, tambi\u00e9n podr\u00eda ser un perfecto acompa\u00f1ante de toda la noche y no solo para el brindis.<\/p>\n<p style=\"text-align: right;\" align=\"justify\"><strong>Lo caro no siempre es lo mejor<\/strong><\/p>\n<p align=\"justify\">Un punto importante es decir que no es necesario gastarse mucho dinero, puesto que por menos de 10\u20ac podemos encontrar vinos con una magnifica calidad.<\/p>\n<p align=\"justify\">Tambi\u00e9n comentar que no me olvido de los <strong>Generosos como Finos, Manzanillas, Amontillados<\/strong>, etc. Estos vinos son un magn\u00edfico aperitivo para comenzar con la velada, pero estos vinos, los trataremos en un apartado diferente \u00a1Estad atentos!<\/p>\n<p align=\"justify\"><strong>\u00bfTienes alg\u00fan vino ya pensado que quieras recomendar a los lectores? \u00a1Deja tu comentario y cu\u00e9ntanoslo!<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.<\/p>\n","protected":false},"author":26,"featured_media":7539,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":[],"categories":[417],"tags":[737],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.11 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Los mejores vinos para esta Navidad 2016 | ESAH<\/title>\n<meta name=\"description\" content=\"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los mejores vinos para esta Navidad 2016 | ESAH\" \/>\n<meta property=\"og:description\" content=\"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\" \/>\n<meta property=\"og:site_name\" content=\"Blog de la Escuela ESAH\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/CampusSEAS\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/ESAHEstudiosSuperioresAbiertosdeHosteleria\" \/>\n<meta property=\"article:published_time\" content=\"2016-12-15T08:30:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2016-12-21T10:40:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/vinos-navidades-2016-esah.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"637\" \/>\n\t<meta property=\"og:image:height\" content=\"240\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Antonio Su\u00e1rez Hidalgo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/vinos-navidades-2016-esah.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@ESAH_Hosteleria\" \/>\n<meta name=\"twitter:site\" content=\"@Campus_SEAS\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Antonio Su\u00e1rez Hidalgo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\"},\"author\":{\"name\":\"Antonio Su\u00e1rez Hidalgo\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/8b583f12045b2a3e911cd80acc16481c\"},\"headline\":\"Los mejores vinos para esta Navidad 2016\",\"datePublished\":\"2016-12-15T08:30:43+00:00\",\"dateModified\":\"2016-12-21T10:40:42+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\"},\"wordCount\":549,\"commentCount\":2,\"publisher\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\"},\"keywords\":[\"Vinos\"],\"articleSection\":[\"Enolog\u00eda\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\",\"name\":\"Los mejores vinos para esta Navidad 2016 | ESAH\",\"isPartOf\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#website\"},\"datePublished\":\"2016-12-15T08:30:43+00:00\",\"dateModified\":\"2016-12-21T10:40:42+00:00\",\"description\":\"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.\",\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016\"]}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#website\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/\",\"name\":\"Blog de la Escuela ESAH\",\"description\":\"Blog de la Escuela ESAH, Estudios Superiores Abiertos de Hosteleria\",\"publisher\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.estudiahosteleria.com\/blog\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#organization\",\"name\":\"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg\",\"contentUrl\":\"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg\",\"width\":512,\"height\":512,\"caption\":\"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda\"},\"image\":{\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/CampusSEAS\",\"https:\/\/twitter.com\/Campus_SEAS\",\"https:\/\/www.instagram.com\/campus_seas\",\"http:\/\/www.linkedin.com\/company\/seas-estudios-superiores-abiertos\",\"https:\/\/www.youtube.com\/@Campus_SEAS\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/8b583f12045b2a3e911cd80acc16481c\",\"name\":\"Antonio Su\u00e1rez Hidalgo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/63caaa49d1fe1140325ba30cbaa5b5d1?s=96&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/63caaa49d1fe1140325ba30cbaa5b5d1?s=96&r=g\",\"caption\":\"Antonio Su\u00e1rez Hidalgo\"},\"description\":\"ESAH, Estudios Superiores Abiertos de Hosteler\u00eda es la escuela de restauraci\u00f3n y turismo online de referencia a nivel internacional de La Escuela de Hosteler\u00eda de Sevilla,\u00a0el Grupo Lezama, y SEAS, Estudios Superiores Abiertos (Grupo San Valero). Visita\u00a0EstudiaHosteleria.com\u00a0para consultar nuestra oferta formativa de\u00a0cursos y m\u00e1sters.\u00a0Formaci\u00f3n profesional para el empleo de calidad y accesible para todos.\",\"sameAs\":[\"https:\/\/www.estudiahosteleria.com\",\"https:\/\/www.facebook.com\/ESAHEstudiosSuperioresAbiertosdeHosteleria\",\"https:\/\/twitter.com\/ESAH_Hosteleria\"],\"url\":\"https:\/\/www.estudiahosteleria.com\/blog\/author\/antonio-suarez-hidalgo\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los mejores vinos para esta Navidad 2016 | ESAH","description":"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016","og_locale":"es_ES","og_type":"article","og_title":"Los mejores vinos para esta Navidad 2016 | ESAH","og_description":"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.","og_url":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016","og_site_name":"Blog de la Escuela ESAH","article_publisher":"https:\/\/www.facebook.com\/CampusSEAS","article_author":"https:\/\/www.facebook.com\/ESAHEstudiosSuperioresAbiertosdeHosteleria","article_published_time":"2016-12-15T08:30:43+00:00","article_modified_time":"2016-12-21T10:40:42+00:00","og_image":[{"width":637,"height":240,"url":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/vinos-navidades-2016-esah.jpg","type":"image\/jpeg"}],"author":"Antonio Su\u00e1rez Hidalgo","twitter_card":"summary_large_image","twitter_image":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2016\/12\/vinos-navidades-2016-esah.jpg","twitter_creator":"@ESAH_Hosteleria","twitter_site":"@Campus_SEAS","twitter_misc":{"Escrito por":"Antonio Su\u00e1rez Hidalgo","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016#article","isPartOf":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016"},"author":{"name":"Antonio Su\u00e1rez Hidalgo","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/8b583f12045b2a3e911cd80acc16481c"},"headline":"Los mejores vinos para esta Navidad 2016","datePublished":"2016-12-15T08:30:43+00:00","dateModified":"2016-12-21T10:40:42+00:00","mainEntityOfPage":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016"},"wordCount":549,"commentCount":2,"publisher":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization"},"keywords":["Vinos"],"articleSection":["Enolog\u00eda"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016","url":"https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016","name":"Los mejores vinos para esta Navidad 2016 | ESAH","isPartOf":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#website"},"datePublished":"2016-12-15T08:30:43+00:00","dateModified":"2016-12-21T10:40:42+00:00","description":"\u00bfBuscamos vinos diferentes estas Navidades? Te proponemos algunas opciones diferentes de vinos y espumosos para estas fiestas: blancos, tintos y espumosos.","inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.estudiahosteleria.com\/blog\/enologia\/los-mejores-vinos-para-esta-navidad-2016"]}]},{"@type":"WebSite","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#website","url":"https:\/\/www.estudiahosteleria.com\/blog\/","name":"Blog de la Escuela ESAH","description":"Blog de la Escuela ESAH, Estudios Superiores Abiertos de Hosteleria","publisher":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.estudiahosteleria.com\/blog\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#organization","name":"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda","url":"https:\/\/www.estudiahosteleria.com\/blog\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/","url":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg","contentUrl":"https:\/\/www.estudiahosteleria.com\/blog\/wp-content\/uploads\/2018\/11\/imagen_twitter_blog_esah.jpg","width":512,"height":512,"caption":"ESAH, Estudios Superiores Abiertos en Hosteler\u00eda"},"image":{"@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/CampusSEAS","https:\/\/twitter.com\/Campus_SEAS","https:\/\/www.instagram.com\/campus_seas","http:\/\/www.linkedin.com\/company\/seas-estudios-superiores-abiertos","https:\/\/www.youtube.com\/@Campus_SEAS"]},{"@type":"Person","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/8b583f12045b2a3e911cd80acc16481c","name":"Antonio Su\u00e1rez Hidalgo","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.estudiahosteleria.com\/blog\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/63caaa49d1fe1140325ba30cbaa5b5d1?s=96&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/63caaa49d1fe1140325ba30cbaa5b5d1?s=96&r=g","caption":"Antonio Su\u00e1rez Hidalgo"},"description":"ESAH, Estudios Superiores Abiertos de Hosteler\u00eda es la escuela de restauraci\u00f3n y turismo online de referencia a nivel internacional de La Escuela de Hosteler\u00eda de Sevilla,\u00a0el Grupo Lezama, y SEAS, Estudios Superiores Abiertos (Grupo San Valero). Visita\u00a0EstudiaHosteleria.com\u00a0para consultar nuestra oferta formativa de\u00a0cursos y m\u00e1sters.\u00a0Formaci\u00f3n profesional para el empleo de calidad y accesible para todos.","sameAs":["https:\/\/www.estudiahosteleria.com","https:\/\/www.facebook.com\/ESAHEstudiosSuperioresAbiertosdeHosteleria","https:\/\/twitter.com\/ESAH_Hosteleria"],"url":"https:\/\/www.estudiahosteleria.com\/blog\/author\/antonio-suarez-hidalgo"}]}},"_links":{"self":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/7453"}],"collection":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/comments?post=7453"}],"version-history":[{"count":10,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/7453\/revisions"}],"predecessor-version":[{"id":7543,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/posts\/7453\/revisions\/7543"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/media\/7539"}],"wp:attachment":[{"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/media?parent=7453"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/categories?post=7453"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.estudiahosteleria.com\/blog\/wp-json\/wp\/v2\/tags?post=7453"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}